
{"id":985,"date":"2022-07-04T17:38:27","date_gmt":"2022-07-04T20:38:27","guid":{"rendered":"https:\/\/www.dbk.net.br\/?p=985"},"modified":"2022-07-08T12:33:16","modified_gmt":"2022-07-08T15:33:16","slug":"1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo","status":"publish","type":"post","link":"https:\/\/www.dbk.net.br\/en\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/","title":{"rendered":"1\u00ba semestre chega ao fim com mercado automotivo descendo ladeira abaixo"},"content":{"rendered":"<h3><\/h3>\n<h3 style=\"text-align: left;\">Encerramos o 6\u00ba m\u00eas consecutivo de queda nas vendas, com alta probabilidade de termos iniciado o 7\u00ba m\u00eas de retra\u00e7\u00e3o. Mas, apesar de tudo, tivemos algumas boas not\u00edcias no setor<\/h3>\n<p>Chegamos ao final do primeiro semestre do ano com not\u00edcias nada animadoras para o setor de ve\u00edculos. E como foi o desempenho do segmento neste primeiro semestre?<\/p>\n<p>Encerramos o sexto m\u00eas consecutivo de queda nas vendas, com alta probabilidade de termos acabado de iniciar o s\u00e9timo m\u00eas de retra\u00e7\u00e3o!<\/p>\n<p><a href=\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-986 size-full\" src=\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-1.jpg\" alt=\"\" width=\"1024\" height=\"583\" srcset=\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-1.jpg 1024w, https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-1-300x171.jpg 300w, https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-1-768x437.jpg 768w, https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-1-18x10.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Isso que, usando aquela nossa vis\u00e3o \u201cPoliana\u201d de ver o mundo, a situa\u00e7\u00e3o se encontra \u201cmenos ruim\u201d do que no come\u00e7o do ano!<\/p>\n<p>Se nos primeiros meses a retra\u00e7\u00e3o m\u00e9dia do setor era na casa dos 25%, nos \u00faltimos dois meses registramos uma queda m\u00e9dia de 1,5% \u2013 e essa dever\u00e1 ser a t\u00f4nica do setor daqui at\u00e9 o final do ano, com volume de vendas na ordem de at\u00e9 5% abaixo ao do que foi registrado sobre igual per\u00edodo do ano passado.<\/p>\n<p>Al\u00e9m disso, tendemos at\u00e9 a ter algum poss\u00edvel lampejo de crescimento nas vendas (provavelmente) em agosto e\/ou setembro.<\/p>\n<p><a href=\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-987 size-full\" src=\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-2.jpg\" alt=\"\" width=\"1024\" height=\"637\" srcset=\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-2.jpg 1024w, https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-2-300x187.jpg 300w, https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-2-768x478.jpg 768w, https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-2-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Mas nada que ir\u00e1 fazer o setor se recuperar! Essa \u201crecupera\u00e7\u00e3o\u201d do setor nos meses de maio e junho n\u00e3o foi porque \u201cmelhoramos\u201d. Essa melhora, na real, aconteceu porque a base comparativa do ano passado est\u00e1 muito comprometida.<\/p>\n<p>Agora, a conta \u00e9 saber se a queda nas vendas deste ano ser\u00e1 de um ou dois d\u00edgitos\u2026<\/p>\n<p>Mas o que tivemos de bom neste primeiro semestre? Porque, apesar da queda, sempre tem aquele pessoal que se destaca. E a\u00ed, elaboramos o nosso Top 5.<\/p>\n<p>O grande destaque deste ano \u00e9 que aquelas marcas que \u201cnum passado n\u00e3o t\u00e3o distante\u201d eram dadas como mortas est\u00e3o renascendo como uma f\u00eanix. E quase todas do nosso Top 5 entram nessa categoria.<\/p>\n<p>Na nossa quinta posi\u00e7\u00e3o, com crescimento nas vendas de 14,3% neste primeiro semestre, temos a\u00a0<strong>MITSUBISHI<\/strong>, que vem se destacando no mercado de picapes.<\/p>\n<p>Sua L200 corresponde por quase 70% de todos os carros que a marca vendeu neste semestre. Al\u00e9m disso, eles tiveram a hombridade de arrumar aquela traseira horrorosa do Eclipse Cross e, com isso, conseguiram alavancar o produto.<\/p>\n<p>Na quarta posi\u00e7\u00e3o temos a\u00a0<strong>TOYOTA<\/strong>, com evolu\u00e7\u00e3o de 15,1% nas vendas. O que falar da Toyota? Os japoneses da marca est\u00e3o sempre em crescimento constante. \u00c9 uma das melhores montadoras para se trabalhar. Eles s\u00e3o como aqueles ultramaratonistas: a corrida \u00e9 de 100 km? N\u00e3o se preocupe, porque chegaremos at\u00e9 o final \u201cde boas\u201d. Diferente de outras marcas que adotam a pol\u00edtica do \u201ccavalo paraguaio\u201d: dar aquele tiro fenomenal na largada, e depois desabar\u2026<\/p>\n<p>No caso da Toyota, a grande vit\u00f3ria da marca \u00e9 a eletrifica\u00e7\u00e3o em um pre\u00e7o mais acess\u00edvel dos seus ve\u00edculos. Al\u00e9m do sucesso do seu Corolla Cross (apesar da \u201cmarmita\u201d) e da sua Hilux.<\/p>\n<p>Na terceira posi\u00e7\u00e3o, temos a\u00a0<strong>CAOA CHERY<\/strong>, com crescimento de 22,3% nas vendas. A Caoa Chery \u00e9 um forte exemplo de marca que renasceu das cinzas. Sua entrada no mercado brasileiro foi atrelada aos produtos QQ, Face, Cielo \u2013 que morreram de \u201cmorte matada\u201d e n\u00e3o deixaram saudades!<\/p>\n<p>Mas, depois que o grupo Caoa deu seu \u201ctoque de midas\u201d, a marca renasceu, tendo hoje 2,2% de share em produtos de alto valor (especialmente com a linha de SUV) e, agora, come\u00e7ando com a eletrifica\u00e7\u00e3o de seus produtos.<\/p>\n<p>Na segunda e na primeir\u00edssima posi\u00e7\u00e3o, temos a\u00a0<strong>CITROEN<\/strong>\u00a0e a\u00a0<strong>PEUGEOT<\/strong>, com crescimento nas vendas de 33,4% e 80,5%, respectivamente. Junto com a Mitsubishi e Caoa Chery, as duas marcas francesas foram as que \u201cvoltaram \u00e0 vida\u201d.<\/p>\n<p>De fato, as duas marcas ir\u00e3o quase triplicar o seu volume de vendas num per\u00edodo de dois anos. Elas ser\u00e3o as montadoras que mais cresceram por aqui, saindo de um volume de 27 mil carros em 2020 para cerca de 75 mil ve\u00edculos neste ano. O grande salto foi a mudan\u00e7a de gest\u00e3o da companhia, que mudou da \u00e1gua para o vinho, quando ela se fundiu com o pessoal da Fiat\/Jeep.<\/p>\n<p>Al\u00e9m desse nosso Top 5, temos tamb\u00e9m a men\u00e7\u00e3o honrosa (apesar de estar mais para \u201cmen\u00e7\u00e3o desonrosa\u201d): nestes \u00faltimos dois meses, vale destacar a recupera\u00e7\u00e3o nas vendas da septuagen\u00e1ria\u00a0<strong>VOLKSWAGEN<\/strong>.<\/p>\n<p>A VW que, no come\u00e7o do ano, estava \u201candando por um vale de trevas e morte\u201d parece (?) ter se reencontrado. A marca, que estava caindo mais do que jaca madura e registrou o pior resultado de vendas na sua hist\u00f3ria (em abril), mostrou um excelente poder de recupera\u00e7\u00e3o nestes dois \u00faltimos meses.<\/p>\n<p>O que parece \u00e9 que os germ\u00e2nicos da VW decidiram usar a t\u00e1tica da blitzkrieg para recuperar todo o terreno que eles perderam no come\u00e7o deste ano.<\/p>\n<p><a href=\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-988 size-full\" src=\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-3.jpg\" alt=\"\" width=\"1024\" height=\"613\" srcset=\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-3.jpg 1024w, https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-3-300x180.jpg 300w, https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-3-768x460.jpg 768w, https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/img-3-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>L\u00f3gico que sab\u00edamos de toda capacidade que os germ\u00e2nicos da VW t\u00eam para sa\u00edrem do seu inferno astral (Marte estava em Merc\u00fario retr\u00f3gado para eles no come\u00e7o deste ano). Tanto que eles dobraram o seu volume de vendas em maio e mantiveram o ritmo em junho.<\/p>\n<p>O questionamento que fazermos \u00e9: at\u00e9 que ponto eles ir\u00e3o continuar no ritmo atual? Em junho, o autom\u00f3vel mais vendido da marca foi o m\u00edtico Gol, com quase 9,5 mil unidades comercializadas (ali\u00e1s: o Gol foi o autom\u00f3vel mais vendido do pa\u00eds se excluirmos os comerciais leves, como as picapes.<\/p>\n<p>Considerando-as, o carro mais vendido continua sendo a Fiat \u201cpato\u201d Strada, que teve 9,8 mil unidades vendidas).<\/p>\n<p>S\u00f3 que o Gol j\u00e1 est\u00e1 com vel\u00f3rio marcado para o final deste ano. At\u00e9 que ponto a VW vai conseguir manter essa pegada?<\/p>\n<p>N\u00e3o sabemos. Mas, apesar dos pesares, fica aqui a nossa men\u00e7\u00e3o honrosa (?) para a VW por essa retomada gigantesca nestes dois \u00faltimos meses.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\"><strong>Fonte: <\/strong><a href=\"https:\/\/www.infomoney.com.br\/colunistas\/o-mundo-sobre-muitas-rodas\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/\">https:\/\/www.infomoney.com.br\/colunistas\/o-mundo-sobre-muitas-rodas\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/<\/a><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Encerramos o 6\u00ba m\u00eas consecutivo de queda nas vendas, com alta probabilidade de termos iniciado o 7\u00ba m\u00eas de retra\u00e7\u00e3o. Mas, apesar de tudo, tivemos algumas boas not\u00edcias no setor Chegamos ao final do primeiro semestre do ano com not\u00edcias nada animadoras para o setor de ve\u00edculos. E como foi o desempenho do segmento neste [&hellip;]<\/p>","protected":false},"author":6,"featured_media":989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>1\u00ba semestre chega ao fim com mercado automotivo descendo ladeira abaixo - DBK<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dbk.net.br\/en\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1\u00ba semestre chega ao fim com mercado automotivo descendo ladeira abaixo - DBK\" \/>\n<meta property=\"og:description\" content=\"Encerramos o 6\u00ba m\u00eas consecutivo de queda nas vendas, com alta probabilidade de termos iniciado o 7\u00ba m\u00eas de retra\u00e7\u00e3o. Mas, apesar de tudo, tivemos algumas boas not\u00edcias no setor Chegamos ao final do primeiro semestre do ano com not\u00edcias nada animadoras para o setor de ve\u00edculos. E como foi o desempenho do segmento neste [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dbk.net.br\/en\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/\" \/>\n<meta property=\"og:site_name\" content=\"DBK\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-04T20:38:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-08T15:33:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/27104-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1117\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Agenor Ferane\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agenor Ferane\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/\",\"url\":\"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/\",\"name\":\"1\u00ba semestre chega ao fim com mercado automotivo descendo ladeira abaixo - DBK\",\"isPartOf\":{\"@id\":\"https:\/\/www.dbk.net.br\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/27104-scaled.jpg\",\"datePublished\":\"2022-07-04T20:38:27+00:00\",\"dateModified\":\"2022-07-08T15:33:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.dbk.net.br\/en\/#\/schema\/person\/cd457086c7388558d43df03aa15ae38d\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/#primaryimage\",\"url\":\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/27104-scaled.jpg\",\"contentUrl\":\"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/27104-scaled.jpg\",\"width\":2560,\"height\":1117},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.dbk.net.br\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1\u00ba semestre chega ao fim com mercado automotivo descendo ladeira abaixo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dbk.net.br\/en\/#website\",\"url\":\"https:\/\/www.dbk.net.br\/en\/\",\"name\":\"DBK\",\"description\":\"Dealership Brokers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dbk.net.br\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dbk.net.br\/en\/#\/schema\/person\/cd457086c7388558d43df03aa15ae38d\",\"name\":\"Agenor Ferane\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.dbk.net.br\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6fba16e55e52adc5f8be1d35aca137de0486b8604c4804eed9df85560a0732fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6fba16e55e52adc5f8be1d35aca137de0486b8604c4804eed9df85560a0732fe?s=96&d=mm&r=g\",\"caption\":\"Agenor Ferane\"},\"sameAs\":[\"http:\/\/www.ncoisas.digital\"],\"url\":\"https:\/\/www.dbk.net.br\/en\/author\/agenorferane\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1\u00ba semestre chega ao fim com mercado automotivo descendo ladeira abaixo - DBK","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dbk.net.br\/en\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/","og_locale":"en_US","og_type":"article","og_title":"1\u00ba semestre chega ao fim com mercado automotivo descendo ladeira abaixo - DBK","og_description":"Encerramos o 6\u00ba m\u00eas consecutivo de queda nas vendas, com alta probabilidade de termos iniciado o 7\u00ba m\u00eas de retra\u00e7\u00e3o. Mas, apesar de tudo, tivemos algumas boas not\u00edcias no setor Chegamos ao final do primeiro semestre do ano com not\u00edcias nada animadoras para o setor de ve\u00edculos. E como foi o desempenho do segmento neste [&hellip;]","og_url":"https:\/\/www.dbk.net.br\/en\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/","og_site_name":"DBK","article_published_time":"2022-07-04T20:38:27+00:00","article_modified_time":"2022-07-08T15:33:16+00:00","og_image":[{"width":2560,"height":1117,"url":"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/27104-scaled.jpg","type":"image\/jpeg"}],"author":"Agenor Ferane","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Agenor Ferane","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/","url":"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/","name":"1\u00ba semestre chega ao fim com mercado automotivo descendo ladeira abaixo - DBK","isPartOf":{"@id":"https:\/\/www.dbk.net.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/#primaryimage"},"image":{"@id":"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/27104-scaled.jpg","datePublished":"2022-07-04T20:38:27+00:00","dateModified":"2022-07-08T15:33:16+00:00","author":{"@id":"https:\/\/www.dbk.net.br\/en\/#\/schema\/person\/cd457086c7388558d43df03aa15ae38d"},"breadcrumb":{"@id":"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/#primaryimage","url":"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/27104-scaled.jpg","contentUrl":"https:\/\/www.dbk.net.br\/wp-content\/uploads\/2022\/07\/27104-scaled.jpg","width":2560,"height":1117},{"@type":"BreadcrumbList","@id":"https:\/\/www.dbk.net.br\/blog\/1o-semestre-chega-ao-fim-com-mercado-automotivo-descendo-ladeira-abaixo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.dbk.net.br\/en\/"},{"@type":"ListItem","position":2,"name":"1\u00ba semestre chega ao fim com mercado automotivo descendo ladeira abaixo"}]},{"@type":"WebSite","@id":"https:\/\/www.dbk.net.br\/en\/#website","url":"https:\/\/www.dbk.net.br\/en\/","name":"DBK","description":"Dealership Brokers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dbk.net.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.dbk.net.br\/en\/#\/schema\/person\/cd457086c7388558d43df03aa15ae38d","name":"Agenor Ferane","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dbk.net.br\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6fba16e55e52adc5f8be1d35aca137de0486b8604c4804eed9df85560a0732fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fba16e55e52adc5f8be1d35aca137de0486b8604c4804eed9df85560a0732fe?s=96&d=mm&r=g","caption":"Agenor Ferane"},"sameAs":["http:\/\/www.ncoisas.digital"],"url":"https:\/\/www.dbk.net.br\/en\/author\/agenorferane\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dbk.net.br\/en\/wp-json\/wp\/v2\/posts\/985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbk.net.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dbk.net.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dbk.net.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dbk.net.br\/en\/wp-json\/wp\/v2\/comments?post=985"}],"version-history":[{"count":34,"href":"https:\/\/www.dbk.net.br\/en\/wp-json\/wp\/v2\/posts\/985\/revisions"}],"predecessor-version":[{"id":1023,"href":"https:\/\/www.dbk.net.br\/en\/wp-json\/wp\/v2\/posts\/985\/revisions\/1023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dbk.net.br\/en\/wp-json\/wp\/v2\/media\/989"}],"wp:attachment":[{"href":"https:\/\/www.dbk.net.br\/en\/wp-json\/wp\/v2\/media?parent=985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dbk.net.br\/en\/wp-json\/wp\/v2\/categories?post=985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dbk.net.br\/en\/wp-json\/wp\/v2\/tags?post=985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}